{"id":2,"date":"2019-11-18T10:29:25","date_gmt":"2019-11-18T09:29:25","guid":{"rendered":"https:\/\/www.scandolamarmi.it\/site\/?page_id=2"},"modified":"2021-08-03T10:21:15","modified_gmt":"2021-08-03T08:21:15","slug":"home-en","status":"publish","type":"page","link":"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/","title":{"rendered":"Home"},"content":{"rendered":"\r\n<p>&nbsp;<\/p>\r\n<div style=\"width: 100px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video muted class=\"wp-video-shortcode\" id=\"video-2-1\" width=\"100\" height=\"100\" loop=\"1\" autoplay=\"1\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.scandolamarmi.it\/site\/wp-content\/uploads\/SCANDOLAMARMI.mp4?_=1\" \/><a href=\"https:\/\/www.scandolamarmi.it\/site\/wp-content\/uploads\/SCANDOLAMARMI.mp4\">https:\/\/www.scandolamarmi.it\/site\/wp-content\/uploads\/SCANDOLAMARMI.mp4<\/a><\/video><\/div>\r\n<h2>Vuoi un prodotto di design e su misura?<\/h2>\r\n<h4><a href=\"https:\/\/www.scandolamarmi.it\/site\/lavorazioni-su-misura\/\">Produzione Personalizzata<\/a><\/h4>\r\n<p>Scandola Marmi <strong>studia e taglia su misura <\/strong>marmi, graniti, agglomerati e pietra naturale per creare mobili, oggetti, pavimenti, complementi d\u2019arredo, rivestimenti o finiture uniche per ogni singola richiesta.<\/p>\r\n<h4><a href=\"https:\/\/www.scandolamarmi.it\/site\/materiali\/\">Ricerca dei Materiali<\/a><\/h4>\r\n<p>Scandola Marmi \u00e8 in grado di fornire tagliato e lavorato su misura qualsiasi tipo di pietra naturale e marmo, appoggiandosi a distributori storici che importano da tutto il mondo.<\/p>\r\n<h4><a href=\"https:\/\/www.scandolamarmi.it\/site\/supporto-tecnico\/\">Supporto<\/a><\/h4>\r\n<p>Partendo da un primo studio della fattibilit\u00e0 del prodotto l\u2019azienda\u00a0<strong>aiuta il cliente passo dopo passo<\/strong> nella realizzazione dei propri prodotti in ottica di ottimizzazione dei costi e dei materiali.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Vuoi un prodotto di design e su misura? Produzione Personalizzata Scandola Marmi studia e taglia su misura marmi, graniti, agglomerati e pietra naturale per creare mobili, oggetti, pavimenti, complementi d\u2019arredo, rivestimenti o finiture uniche per ogni singola richiesta. Ricerca dei Materiali Scandola Marmi \u00e8 in grado di fornire tagliato e lavorato su misura qualsiasi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scandola Marmi S.n.c. - Lavorazione Marmo<\/title>\n<meta name=\"description\" content=\"Scandola Marmi dal 1964. Lavorazione su misura di marmo, granito, agglomerati e pietra naturale. Produzione personalizzata. Artigiani. Verona. Made in Italy\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scandola Marmi S.n.c. - Lavorazione Marmo\" \/>\n<meta property=\"og:description\" content=\"Scandola Marmi dal 1964. Lavorazione su misura di marmo, granito, agglomerati e pietra naturale. Produzione personalizzata. Artigiani. Verona. Made in Italy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandola Marmi S.n.c.\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-03T08:21:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data1\" content=\"0 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.scandolamarmi.it\/site\/#website\",\"url\":\"https:\/\/www.scandolamarmi.it\/site\/\",\"name\":\"Scandola Marmi S.n.c.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.scandolamarmi.it\/site\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/#webpage\",\"url\":\"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/\",\"name\":\"Scandola Marmi S.n.c. - Lavorazione Marmo\",\"isPartOf\":{\"@id\":\"https:\/\/www.scandolamarmi.it\/site\/#website\"},\"datePublished\":\"2019-11-18T09:29:25+00:00\",\"dateModified\":\"2021-08-03T08:21:15+00:00\",\"description\":\"Scandola Marmi dal 1964. Lavorazione su misura di marmo, granito, agglomerati e pietra naturale. Produzione personalizzata. Artigiani. Verona. Made in Italy\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.scandolamarmi.it\/site\/it\/home-en\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/pages\/2"}],"collection":[{"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":30,"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":543,"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/pages\/2\/revisions\/543"}],"wp:attachment":[{"href":"https:\/\/www.scandolamarmi.it\/site\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}